{"id":23,"date":"2011-05-02T13:41:41","date_gmt":"2011-05-02T12:41:41","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/biciclettando\/?p=23"},"modified":"2011-05-02T13:41:41","modified_gmt":"2011-05-02T12:41:41","slug":"1%c2%b0-campionato-italiano-della-ciclabilita-urbana","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/biciclettando\/1%c2%b0-campionato-italiano-della-ciclabilita-urbana\/","title":{"rendered":"1\u00b0 Campionato italiano della ciclabilit\u00e0 urbana"},"content":{"rendered":"<p><a href=\"http:\/\/www.quotidianopiemontese.it\/biciclettando\/files\/2011\/04\/logo_giretto_italia.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-26\" src=\"http:\/\/www.quotidianopiemontese.it\/biciclettando\/files\/2011\/04\/logo_giretto_italia.jpg\" alt=\"\" width=\"500\" height=\"281\" \/><\/a>Che cos\u2019\u00e8?\u00a0Una gara tra le citt\u00e0 italiane impegnate a favorire la mobilit\u00e0 ciclabile urbana. Vincer\u00e0 quella in cui, in occasione del Giretto d\u2019Italia, si sposter\u00e0 in bicicletta il maggior numero di persone in proporzione agli abitanti.\u00a0Il Giretto d\u2019Italia vuole dimostrare che la mobilit\u00e0 in bici \u00e8 possibile e vuole dare\u00a0alle positive esperienze locali una dimensione nazionale, segnalando che c\u2019\u00e8 un paese pronto per una mobilit\u00e0 dolce, diversa, pi\u00f9 sana, pi\u00f9 sostenibile, pi\u00f9 sicura.<\/p>\n<p>L\u2019appuntamento \u00e8 per marted\u00ec 3 maggio,\u00a0tra le 7.30 e le 9.30.\u00a0Ogni Comune aderente organizzer\u00e0 tre check-point in tre zone diverse della citt\u00e0 per monitorare tutti i veicoli in transito. La citt\u00e0 guadagner\u00e0 punti ogni volta che passer\u00e0 una bicicletta, mentre ricever\u00e0 bonus quando passeranno pedoni e bus. Saranno invece attribuite penalit\u00e0 quando transiteranno automobili e scooter.<\/p>\n<p>A Torino l\u2019iniziativa \u00e8 organizzata e coordinata dall\u2019Ufficio Biciclette della Citt\u00e0. I 3 punti di monitoraggio individuati sono:<\/p>\n<ul>\n<li>c.so Francia angolo via Principi d\u2019Acaja\u00a0 &#8211; direzione Piazza Statuto<\/li>\n<li>viale Primo Maggio (pista dei Giardini Reali) \u2013 direzione Piazza Castello<\/li>\n<li>via Verdi angolo via Roero di Cortanze<\/li>\n<\/ul>\n<p>I 3 punti torinesi saranno presidiati da volontari di Legambiente, Associaizone Bici &amp; Dintorni, Associazione Amici della Bicicletta, Associazione Intorno,\u00a0e Muovi Equilibri.\u00a0Nei check-point saranno a disposizione gratuita mappe delle piste ciclabili, un adesivo ricordo e un frutto a Km 0 offerto da Coldiretti.<\/p>\n<p>La\u00a0premiazione verr\u00e0 effettuata domenica 8 maggio\u00a0a Roma presso il Ministero dell\u2019Ambiente, nell\u2019ambito della Giornata Nazionale della Bicicletta.\u00a0Il Giretto d\u2019Italia \u00e8 un\u2019iniziativa di\u00a0Legambiente, Citt\u00e0 in Bici (Coordinamento Nazionale Uffici Biciclette \u2013 A21Italy) e FIAB, con il patrocinio del Ministero dell\u2019Ambiente, organizzata insieme ai 27 Comuni aderenti: Bari, Bolzano, Carpi, Ferrara, Firenze, Grosseto, Genova, La Spezia, Lodi, Milano, Modena, Monfalcone, Padova, Parma, Pisa, Pordenone, Ravenna, Reggio Emilia, Roma, Schio, Senigallia, Trento, Torino, Udine, Venezia, Verona, Vicenza.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Che cos\u2019\u00e8?\u00a0Una gara tra le citt\u00e0 italiane impegnate a favorire la mobilit\u00e0 ciclabile urbana. Vincer\u00e0 quella in cui, in occasione del Giretto d\u2019Italia, si sposter\u00e0 in bicicletta il maggior numero di persone in proporzione agli abitanti.\u00a0Il Giretto d\u2019Italia vuole dimostrare che la mobilit\u00e0 in bici \u00e8 possibile e vuole dare\u00a0alle positive esperienze locali una dimensione &hellip; <a href=\"https:\/\/web.quotidianopiemontese.it\/biciclettando\/1%c2%b0-campionato-italiano-della-ciclabilita-urbana\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;1\u00b0 Campionato italiano della ciclabilit\u00e0 urbana&#8221;<\/span><\/a><\/p>\n","protected":false},"author":103,"featured_media":26,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-23","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-biciclettando"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>1\u00b0 Campionato italiano della ciclabilit\u00e0 urbana  - Biciclettando<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/web.quotidianopiemontese.it\/biciclettando\/1\u00b0-campionato-italiano-della-ciclabilita-urbana\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"1\u00b0 Campionato italiano della ciclabilit\u00e0 urbana  - Biciclettando\" \/>\n<meta property=\"og:url\" content=\"http:\/\/web.quotidianopiemontese.it\/biciclettando\/1\u00b0-campionato-italiano-della-ciclabilita-urbana\/\" \/>\n<meta property=\"og:site_name\" content=\"Biciclettando\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:published_time\" content=\"2011-05-02T12:41:41+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/web.quotidianopiemontese.it\/biciclettando\/files\/2011\/04\/logo_giretto_italia.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"281\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gaia D&#039;Asti\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gaia D&#039;Asti\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/biciclettando\\\/1%c2%b0-campionato-italiano-della-ciclabilita-urbana\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/biciclettando\\\/1%c2%b0-campionato-italiano-della-ciclabilita-urbana\\\/\"},\"author\":{\"name\":\"Gaia D'Asti\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/biciclettando\\\/#\\\/schema\\\/person\\\/706bd8ab7d71e4161df25ae2aee00c85\"},\"headline\":\"1\u00b0 Campionato italiano della ciclabilit\u00e0 urbana\",\"datePublished\":\"2011-05-02T12:41:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/biciclettando\\\/1%c2%b0-campionato-italiano-della-ciclabilita-urbana\\\/\"},\"wordCount\":309,\"commentCount\":0,\"image\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/biciclettando\\\/1%c2%b0-campionato-italiano-della-ciclabilita-urbana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/biciclettando\\\/files\\\/2011\\\/04\\\/logo_giretto_italia.jpg\",\"articleSection\":[\"Biciclettando\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/web.quotidianopiemontese.it\\\/biciclettando\\\/1%c2%b0-campionato-italiano-della-ciclabilita-urbana\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/biciclettando\\\/1%c2%b0-campionato-italiano-della-ciclabilita-urbana\\\/\",\"url\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/biciclettando\\\/1%c2%b0-campionato-italiano-della-ciclabilita-urbana\\\/\",\"name\":\"1\u00b0 Campionato italiano della ciclabilit\u00e0 urbana - Biciclettando\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/biciclettando\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/biciclettando\\\/1%c2%b0-campionato-italiano-della-ciclabilita-urbana\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/biciclettando\\\/1%c2%b0-campionato-italiano-della-ciclabilita-urbana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/biciclettando\\\/files\\\/2011\\\/04\\\/logo_giretto_italia.jpg\",\"datePublished\":\"2011-05-02T12:41:41+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/biciclettando\\\/#\\\/schema\\\/person\\\/706bd8ab7d71e4161df25ae2aee00c85\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/biciclettando\\\/1%c2%b0-campionato-italiano-della-ciclabilita-urbana\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/web.quotidianopiemontese.it\\\/biciclettando\\\/1%c2%b0-campionato-italiano-della-ciclabilita-urbana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/biciclettando\\\/1%c2%b0-campionato-italiano-della-ciclabilita-urbana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/biciclettando\\\/files\\\/2011\\\/04\\\/logo_giretto_italia.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/biciclettando\\\/files\\\/2011\\\/04\\\/logo_giretto_italia.jpg\",\"width\":\"600\",\"height\":\"281\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/biciclettando\\\/1%c2%b0-campionato-italiano-della-ciclabilita-urbana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/biciclettando\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"1\u00b0 Campionato italiano della ciclabilit\u00e0 urbana\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/biciclettando\\\/#website\",\"url\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/biciclettando\\\/\",\"name\":\"Biciclettando\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/biciclettando\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/biciclettando\\\/#\\\/schema\\\/person\\\/706bd8ab7d71e4161df25ae2aee00c85\",\"name\":\"Gaia D'Asti\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00ea833a68a879b8406f3f9c31650829dc0655cc5db7cab7a6b26bd32f25ccd6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00ea833a68a879b8406f3f9c31650829dc0655cc5db7cab7a6b26bd32f25ccd6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/00ea833a68a879b8406f3f9c31650829dc0655cc5db7cab7a6b26bd32f25ccd6?s=96&d=mm&r=g\",\"caption\":\"Gaia D'Asti\"},\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/biciclettando\\\/author\\\/gaiadasti\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"1\u00b0 Campionato italiano della ciclabilit\u00e0 urbana  - Biciclettando","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/web.quotidianopiemontese.it\/biciclettando\/1\u00b0-campionato-italiano-della-ciclabilita-urbana\/","og_locale":"it_IT","og_type":"article","og_title":"1\u00b0 Campionato italiano della ciclabilit\u00e0 urbana  - Biciclettando","og_url":"http:\/\/web.quotidianopiemontese.it\/biciclettando\/1\u00b0-campionato-italiano-della-ciclabilita-urbana\/","og_site_name":"Biciclettando","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_published_time":"2011-05-02T12:41:41+00:00","og_image":[{"width":600,"height":281,"url":"http:\/\/web.quotidianopiemontese.it\/biciclettando\/files\/2011\/04\/logo_giretto_italia.jpg","type":"image\/jpeg"}],"author":"Gaia D'Asti","twitter_misc":{"Scritto da":"Gaia D'Asti","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/web.quotidianopiemontese.it\/biciclettando\/1%c2%b0-campionato-italiano-della-ciclabilita-urbana\/#article","isPartOf":{"@id":"http:\/\/web.quotidianopiemontese.it\/biciclettando\/1%c2%b0-campionato-italiano-della-ciclabilita-urbana\/"},"author":{"name":"Gaia D'Asti","@id":"http:\/\/web.quotidianopiemontese.it\/biciclettando\/#\/schema\/person\/706bd8ab7d71e4161df25ae2aee00c85"},"headline":"1\u00b0 Campionato italiano della ciclabilit\u00e0 urbana","datePublished":"2011-05-02T12:41:41+00:00","mainEntityOfPage":{"@id":"http:\/\/web.quotidianopiemontese.it\/biciclettando\/1%c2%b0-campionato-italiano-della-ciclabilita-urbana\/"},"wordCount":309,"commentCount":0,"image":{"@id":"http:\/\/web.quotidianopiemontese.it\/biciclettando\/1%c2%b0-campionato-italiano-della-ciclabilita-urbana\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/biciclettando\/files\/2011\/04\/logo_giretto_italia.jpg","articleSection":["Biciclettando"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/web.quotidianopiemontese.it\/biciclettando\/1%c2%b0-campionato-italiano-della-ciclabilita-urbana\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/web.quotidianopiemontese.it\/biciclettando\/1%c2%b0-campionato-italiano-della-ciclabilita-urbana\/","url":"http:\/\/web.quotidianopiemontese.it\/biciclettando\/1%c2%b0-campionato-italiano-della-ciclabilita-urbana\/","name":"1\u00b0 Campionato italiano della ciclabilit\u00e0 urbana - Biciclettando","isPartOf":{"@id":"http:\/\/web.quotidianopiemontese.it\/biciclettando\/#website"},"primaryImageOfPage":{"@id":"http:\/\/web.quotidianopiemontese.it\/biciclettando\/1%c2%b0-campionato-italiano-della-ciclabilita-urbana\/#primaryimage"},"image":{"@id":"http:\/\/web.quotidianopiemontese.it\/biciclettando\/1%c2%b0-campionato-italiano-della-ciclabilita-urbana\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/biciclettando\/files\/2011\/04\/logo_giretto_italia.jpg","datePublished":"2011-05-02T12:41:41+00:00","author":{"@id":"http:\/\/web.quotidianopiemontese.it\/biciclettando\/#\/schema\/person\/706bd8ab7d71e4161df25ae2aee00c85"},"breadcrumb":{"@id":"http:\/\/web.quotidianopiemontese.it\/biciclettando\/1%c2%b0-campionato-italiano-della-ciclabilita-urbana\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/web.quotidianopiemontese.it\/biciclettando\/1%c2%b0-campionato-italiano-della-ciclabilita-urbana\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"http:\/\/web.quotidianopiemontese.it\/biciclettando\/1%c2%b0-campionato-italiano-della-ciclabilita-urbana\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/biciclettando\/files\/2011\/04\/logo_giretto_italia.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/biciclettando\/files\/2011\/04\/logo_giretto_italia.jpg","width":"600","height":"281"},{"@type":"BreadcrumbList","@id":"http:\/\/web.quotidianopiemontese.it\/biciclettando\/1%c2%b0-campionato-italiano-della-ciclabilita-urbana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/web.quotidianopiemontese.it\/biciclettando\/"},{"@type":"ListItem","position":2,"name":"1\u00b0 Campionato italiano della ciclabilit\u00e0 urbana"}]},{"@type":"WebSite","@id":"http:\/\/web.quotidianopiemontese.it\/biciclettando\/#website","url":"http:\/\/web.quotidianopiemontese.it\/biciclettando\/","name":"Biciclettando","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/web.quotidianopiemontese.it\/biciclettando\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"http:\/\/web.quotidianopiemontese.it\/biciclettando\/#\/schema\/person\/706bd8ab7d71e4161df25ae2aee00c85","name":"Gaia D'Asti","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/00ea833a68a879b8406f3f9c31650829dc0655cc5db7cab7a6b26bd32f25ccd6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/00ea833a68a879b8406f3f9c31650829dc0655cc5db7cab7a6b26bd32f25ccd6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/00ea833a68a879b8406f3f9c31650829dc0655cc5db7cab7a6b26bd32f25ccd6?s=96&d=mm&r=g","caption":"Gaia D'Asti"},"url":"https:\/\/web.quotidianopiemontese.it\/biciclettando\/author\/gaiadasti\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/biciclettando\/wp-json\/wp\/v2\/posts\/23","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/biciclettando\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/biciclettando\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/biciclettando\/wp-json\/wp\/v2\/users\/103"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/biciclettando\/wp-json\/wp\/v2\/comments?post=23"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/biciclettando\/wp-json\/wp\/v2\/posts\/23\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/biciclettando\/wp-json\/wp\/v2\/media\/26"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/biciclettando\/wp-json\/wp\/v2\/media?parent=23"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/biciclettando\/wp-json\/wp\/v2\/categories?post=23"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/biciclettando\/wp-json\/wp\/v2\/tags?post=23"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}