{"id":438,"date":"2019-05-05T16:23:36","date_gmt":"2019-05-05T14:23:36","guid":{"rendered":"http:\/\/web.quotidianopiemontese.it\/avventure-semiserie-mie-gambe\/?p=438"},"modified":"2019-05-05T16:23:36","modified_gmt":"2019-05-05T14:23:36","slug":"che-bella-sorpresa-iacopo-melio-su-topolino","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/avventure-semiserie-mie-gambe\/che-bella-sorpresa-iacopo-melio-su-topolino\/","title":{"rendered":"Che bella sorpresa: Iacopo Melio su Topolino!"},"content":{"rendered":"<p>In realt\u00e0 lo sapevo gi\u00e0 perch\u00e9 lo aveva preannunciato lo stesso <strong>Iacopo su Facebook.\u00a0<\/strong>\u00c9 stato comunque emozionante vedere che il mio\u00a0<strong>amato giornalino della Panini avesse scelto di dedicare il primo numero della rubrica proprio a Iacopo.\u00a0<\/strong>Il ragazzo \u00e8 conosciuto per la sua campagna contro le barriere architettoniche #vorreiprendereiltreno e parlarne su un giornale per ragazzi, fa proprio parte delle\u00a0<strong>azioni concrete per la diffusione della cultura della disabilit\u00e0 di cui parlo spesso.\u00a0<\/strong>Complimenti dunque al direttore di Topolino! Mi permetterei di formulare anche un suggerimento. La prossima volta <strong>Iacopo dovr\u00e0 partecipare come protagonista di una storia a fumetti! Mi sembra il minimo. Forza autori, pensateci!<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>In realt\u00e0 lo sapevo gi\u00e0 perch\u00e9 lo aveva preannunciato lo stesso Iacopo su Facebook.\u00a0\u00c9 stato comunque emozionante vedere che il mio\u00a0amato giornalino della Panini avesse scelto di dedicare il primo numero della rubrica proprio a Iacopo.\u00a0Il ragazzo \u00e8 conosciuto per la sua campagna contro le barriere architettoniche #vorreiprendereiltreno e parlarne su un giornale per ragazzi, &hellip; <a href=\"https:\/\/web.quotidianopiemontese.it\/avventure-semiserie-mie-gambe\/che-bella-sorpresa-iacopo-melio-su-topolino\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;Che bella sorpresa: Iacopo Melio su Topolino!&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1366,"featured_media":439,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[146,55,148,6,72,147],"class_list":["post-438","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-avventure-delle-mie-gambe","tag-vorreiprendereiltreno","tag-barriere-architettoniche","tag-cultura-della-disabilita","tag-disabilita","tag-iacopo-melio","tag-topolino"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Che bella sorpresa: Iacopo Melio su Topolino! - Avventure semiserie delle mie gambe<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/avventure-semiserie-mie-gambe\/che-bella-sorpresa-iacopo-melio-su-topolino\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Che bella sorpresa: Iacopo Melio su Topolino! - Avventure semiserie delle mie gambe\" \/>\n<meta property=\"og:description\" content=\"In realt\u00e0 lo sapevo gi\u00e0 perch\u00e9 lo aveva preannunciato lo stesso Iacopo su Facebook.\u00a0\u00c9 stato comunque emozionante vedere che il mio\u00a0amato giornalino della Panini avesse scelto di dedicare il primo numero della rubrica proprio a Iacopo.\u00a0Il ragazzo \u00e8 conosciuto per la sua campagna contro le barriere architettoniche #vorreiprendereiltreno e parlarne su un giornale per ragazzi, &hellip; Leggi tutto &quot;Che bella sorpresa: Iacopo Melio su Topolino!&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/avventure-semiserie-mie-gambe\/che-bella-sorpresa-iacopo-melio-su-topolino\/\" \/>\n<meta property=\"og:site_name\" content=\"Avventure semiserie delle mie gambe\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-05T14:23:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/web.quotidianopiemontese.it\/avventure-semiserie-mie-gambe\/files\/2019\/05\/IMG_20190505_120631.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2934\" \/>\n\t<meta property=\"og:image:height\" content=\"2059\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Noria Nalli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@quotidianopiem\" \/>\n<meta name=\"twitter:site\" content=\"@quotidianopiem\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noria Nalli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/avventure-semiserie-mie-gambe\\\/che-bella-sorpresa-iacopo-melio-su-topolino\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/avventure-semiserie-mie-gambe\\\/che-bella-sorpresa-iacopo-melio-su-topolino\\\/\"},\"author\":{\"name\":\"Noria Nalli\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/avventure-semiserie-mie-gambe\\\/#\\\/schema\\\/person\\\/3c6eb480b56f6d813145e6aac695ccf2\"},\"headline\":\"Che bella sorpresa: Iacopo Melio su Topolino!\",\"datePublished\":\"2019-05-05T14:23:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/avventure-semiserie-mie-gambe\\\/che-bella-sorpresa-iacopo-melio-su-topolino\\\/\"},\"wordCount\":113,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/avventure-semiserie-mie-gambe\\\/che-bella-sorpresa-iacopo-melio-su-topolino\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/avventure-semiserie-mie-gambe\\\/files\\\/2019\\\/05\\\/IMG_20190505_120631.jpg\",\"keywords\":[\"#vorreiprendereiltreno\",\"barriere architettoniche\",\"cultura della disabilit\u00e0\",\"disabilit\u00e0\",\"Iacopo Melio\",\"Topolino\"],\"articleSection\":[\"Avventure delle mie Gambe\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/avventure-semiserie-mie-gambe\\\/che-bella-sorpresa-iacopo-melio-su-topolino\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/avventure-semiserie-mie-gambe\\\/che-bella-sorpresa-iacopo-melio-su-topolino\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/avventure-semiserie-mie-gambe\\\/che-bella-sorpresa-iacopo-melio-su-topolino\\\/\",\"name\":\"Che bella sorpresa: Iacopo Melio su Topolino! - Avventure semiserie delle mie gambe\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/avventure-semiserie-mie-gambe\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/avventure-semiserie-mie-gambe\\\/che-bella-sorpresa-iacopo-melio-su-topolino\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/avventure-semiserie-mie-gambe\\\/che-bella-sorpresa-iacopo-melio-su-topolino\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/avventure-semiserie-mie-gambe\\\/files\\\/2019\\\/05\\\/IMG_20190505_120631.jpg\",\"datePublished\":\"2019-05-05T14:23:36+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/avventure-semiserie-mie-gambe\\\/#\\\/schema\\\/person\\\/3c6eb480b56f6d813145e6aac695ccf2\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/avventure-semiserie-mie-gambe\\\/che-bella-sorpresa-iacopo-melio-su-topolino\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/avventure-semiserie-mie-gambe\\\/che-bella-sorpresa-iacopo-melio-su-topolino\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/avventure-semiserie-mie-gambe\\\/che-bella-sorpresa-iacopo-melio-su-topolino\\\/#primaryimage\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/avventure-semiserie-mie-gambe\\\/files\\\/2019\\\/05\\\/IMG_20190505_120631.jpg\",\"contentUrl\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/avventure-semiserie-mie-gambe\\\/files\\\/2019\\\/05\\\/IMG_20190505_120631.jpg\",\"width\":2934,\"height\":2059,\"caption\":\"All-focus\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/avventure-semiserie-mie-gambe\\\/che-bella-sorpresa-iacopo-melio-su-topolino\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/avventure-semiserie-mie-gambe\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Che bella sorpresa: Iacopo Melio su Topolino!\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/avventure-semiserie-mie-gambe\\\/#website\",\"url\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/avventure-semiserie-mie-gambe\\\/\",\"name\":\"Avventure semiserie delle mie gambe\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/avventure-semiserie-mie-gambe\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/avventure-semiserie-mie-gambe\\\/#\\\/schema\\\/person\\\/3c6eb480b56f6d813145e6aac695ccf2\",\"name\":\"Noria Nalli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7b56c9d18dc264ab81e4aab7c8b76f702b0d476b8960e077976466383b8ec0ee?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7b56c9d18dc264ab81e4aab7c8b76f702b0d476b8960e077976466383b8ec0ee?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7b56c9d18dc264ab81e4aab7c8b76f702b0d476b8960e077976466383b8ec0ee?s=96&d=mm&r=g\",\"caption\":\"Noria Nalli\"},\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/avventure-semiserie-mie-gambe\\\/author\\\/norianalli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Che bella sorpresa: Iacopo Melio su Topolino! - Avventure semiserie delle mie gambe","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/avventure-semiserie-mie-gambe\/che-bella-sorpresa-iacopo-melio-su-topolino\/","og_locale":"it_IT","og_type":"article","og_title":"Che bella sorpresa: Iacopo Melio su Topolino! - Avventure semiserie delle mie gambe","og_description":"In realt\u00e0 lo sapevo gi\u00e0 perch\u00e9 lo aveva preannunciato lo stesso Iacopo su Facebook.\u00a0\u00c9 stato comunque emozionante vedere che il mio\u00a0amato giornalino della Panini avesse scelto di dedicare il primo numero della rubrica proprio a Iacopo.\u00a0Il ragazzo \u00e8 conosciuto per la sua campagna contro le barriere architettoniche #vorreiprendereiltreno e parlarne su un giornale per ragazzi, &hellip; Leggi tutto \"Che bella sorpresa: Iacopo Melio su Topolino!\"","og_url":"https:\/\/web.quotidianopiemontese.it\/avventure-semiserie-mie-gambe\/che-bella-sorpresa-iacopo-melio-su-topolino\/","og_site_name":"Avventure semiserie delle mie gambe","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese","article_published_time":"2019-05-05T14:23:36+00:00","og_image":[{"width":2934,"height":2059,"url":"https:\/\/web.quotidianopiemontese.it\/avventure-semiserie-mie-gambe\/files\/2019\/05\/IMG_20190505_120631.jpg","type":"image\/jpeg"}],"author":"Noria Nalli","twitter_card":"summary_large_image","twitter_creator":"@quotidianopiem","twitter_site":"@quotidianopiem","twitter_misc":{"Scritto da":"Noria Nalli","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/avventure-semiserie-mie-gambe\/che-bella-sorpresa-iacopo-melio-su-topolino\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/avventure-semiserie-mie-gambe\/che-bella-sorpresa-iacopo-melio-su-topolino\/"},"author":{"name":"Noria Nalli","@id":"http:\/\/web.quotidianopiemontese.it\/avventure-semiserie-mie-gambe\/#\/schema\/person\/3c6eb480b56f6d813145e6aac695ccf2"},"headline":"Che bella sorpresa: Iacopo Melio su Topolino!","datePublished":"2019-05-05T14:23:36+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/avventure-semiserie-mie-gambe\/che-bella-sorpresa-iacopo-melio-su-topolino\/"},"wordCount":113,"commentCount":0,"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/avventure-semiserie-mie-gambe\/che-bella-sorpresa-iacopo-melio-su-topolino\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/avventure-semiserie-mie-gambe\/files\/2019\/05\/IMG_20190505_120631.jpg","keywords":["#vorreiprendereiltreno","barriere architettoniche","cultura della disabilit\u00e0","disabilit\u00e0","Iacopo Melio","Topolino"],"articleSection":["Avventure delle mie Gambe"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/avventure-semiserie-mie-gambe\/che-bella-sorpresa-iacopo-melio-su-topolino\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/avventure-semiserie-mie-gambe\/che-bella-sorpresa-iacopo-melio-su-topolino\/","url":"https:\/\/web.quotidianopiemontese.it\/avventure-semiserie-mie-gambe\/che-bella-sorpresa-iacopo-melio-su-topolino\/","name":"Che bella sorpresa: Iacopo Melio su Topolino! - Avventure semiserie delle mie gambe","isPartOf":{"@id":"http:\/\/web.quotidianopiemontese.it\/avventure-semiserie-mie-gambe\/#website"},"primaryImageOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/avventure-semiserie-mie-gambe\/che-bella-sorpresa-iacopo-melio-su-topolino\/#primaryimage"},"image":{"@id":"https:\/\/web.quotidianopiemontese.it\/avventure-semiserie-mie-gambe\/che-bella-sorpresa-iacopo-melio-su-topolino\/#primaryimage"},"thumbnailUrl":"https:\/\/web.quotidianopiemontese.it\/avventure-semiserie-mie-gambe\/files\/2019\/05\/IMG_20190505_120631.jpg","datePublished":"2019-05-05T14:23:36+00:00","author":{"@id":"http:\/\/web.quotidianopiemontese.it\/avventure-semiserie-mie-gambe\/#\/schema\/person\/3c6eb480b56f6d813145e6aac695ccf2"},"breadcrumb":{"@id":"https:\/\/web.quotidianopiemontese.it\/avventure-semiserie-mie-gambe\/che-bella-sorpresa-iacopo-melio-su-topolino\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/avventure-semiserie-mie-gambe\/che-bella-sorpresa-iacopo-melio-su-topolino\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/web.quotidianopiemontese.it\/avventure-semiserie-mie-gambe\/che-bella-sorpresa-iacopo-melio-su-topolino\/#primaryimage","url":"https:\/\/web.quotidianopiemontese.it\/avventure-semiserie-mie-gambe\/files\/2019\/05\/IMG_20190505_120631.jpg","contentUrl":"https:\/\/web.quotidianopiemontese.it\/avventure-semiserie-mie-gambe\/files\/2019\/05\/IMG_20190505_120631.jpg","width":2934,"height":2059,"caption":"All-focus"},{"@type":"BreadcrumbList","@id":"https:\/\/web.quotidianopiemontese.it\/avventure-semiserie-mie-gambe\/che-bella-sorpresa-iacopo-melio-su-topolino\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/web.quotidianopiemontese.it\/avventure-semiserie-mie-gambe\/"},{"@type":"ListItem","position":2,"name":"Che bella sorpresa: Iacopo Melio su Topolino!"}]},{"@type":"WebSite","@id":"http:\/\/web.quotidianopiemontese.it\/avventure-semiserie-mie-gambe\/#website","url":"http:\/\/web.quotidianopiemontese.it\/avventure-semiserie-mie-gambe\/","name":"Avventure semiserie delle mie gambe","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/web.quotidianopiemontese.it\/avventure-semiserie-mie-gambe\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"http:\/\/web.quotidianopiemontese.it\/avventure-semiserie-mie-gambe\/#\/schema\/person\/3c6eb480b56f6d813145e6aac695ccf2","name":"Noria Nalli","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/7b56c9d18dc264ab81e4aab7c8b76f702b0d476b8960e077976466383b8ec0ee?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7b56c9d18dc264ab81e4aab7c8b76f702b0d476b8960e077976466383b8ec0ee?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7b56c9d18dc264ab81e4aab7c8b76f702b0d476b8960e077976466383b8ec0ee?s=96&d=mm&r=g","caption":"Noria Nalli"},"url":"https:\/\/web.quotidianopiemontese.it\/avventure-semiserie-mie-gambe\/author\/norianalli\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/avventure-semiserie-mie-gambe\/wp-json\/wp\/v2\/posts\/438","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/avventure-semiserie-mie-gambe\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/avventure-semiserie-mie-gambe\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/avventure-semiserie-mie-gambe\/wp-json\/wp\/v2\/users\/1366"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/avventure-semiserie-mie-gambe\/wp-json\/wp\/v2\/comments?post=438"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/avventure-semiserie-mie-gambe\/wp-json\/wp\/v2\/posts\/438\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/avventure-semiserie-mie-gambe\/wp-json\/wp\/v2\/media\/439"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/avventure-semiserie-mie-gambe\/wp-json\/wp\/v2\/media?parent=438"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/avventure-semiserie-mie-gambe\/wp-json\/wp\/v2\/categories?post=438"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/avventure-semiserie-mie-gambe\/wp-json\/wp\/v2\/tags?post=438"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}