{"id":34,"date":"2015-02-11T09:31:55","date_gmt":"2015-02-11T08:31:55","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/agricoltura-in-piemonte\/?p=34"},"modified":"2015-02-11T01:32:29","modified_gmt":"2015-02-11T00:32:29","slug":"listat-disconosce-la-classificazione-dei-comuni-montani-usata-per-limu-agricola","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/agricoltura-in-piemonte\/listat-disconosce-la-classificazione-dei-comuni-montani-usata-per-limu-agricola\/","title":{"rendered":"L&#8217;Istat disconosce la classificazione dei comuni montani usata per l&#8217;Imu agricola"},"content":{"rendered":"<p>A\u00a0poche ore dalla scadenza dei termini di pagamento dell\u2019Imu agricola, fissati per il \u00a010 febbraio, l\u2019Istat <a href=\"http:\/\/www.istat.it\/it\/archivio\/147760\" target=\"_blank\">ha disconosciuto con una nota ufficiale<\/a>\u00a0di essere responsabile della classificazione dei comuni montani utilizzata per la quantificazione della tassa.<\/p>\n<p>In merito alle notizie pubblicate in questi giorni dai mezzi di informazione, che imputano all&#8217;Istat la classificazione dei comuni montani utilizzata per la quantificazione dell&#8217;IMU, si precisa quanto segue:<\/p>\n<ol>\n<li>\n<blockquote><p>La classificazione per grado di montanit\u00e0, che prevede la suddivisione dei comuni in &#8220;totalmente montani&#8221;, &#8220;parzialmente montani&#8221; e &#8220;non montani&#8221;, non \u00e8 una &#8220;classificazione Istat&#8221; ma l&#8217;esito dell&#8217;applicazione dell&#8217;art. 1 della legge 991\/1952 &#8211; Determinazione dei territori montani (Si veda in proposito: http:\/\/www.simontagna.it\/portalesim\/comunimontani.html#LetteraC). Tale classificazione \u00e8 stata trasmessa all&#8217;Istat dall&#8217;UNCEM (Unione Nazionale Comuni Comunit\u00e0 Enti Montani), come viene anche specificato nelle note dell&#8217;elenco pubblicato, ed \u00e8 stata inclusa tra le informazioni di interesse ai fini dello studio statistico del territorio comunale congiuntamente ai codici statistici comunali.<\/p><\/blockquote>\n<\/li>\n<li>\n<blockquote><p>La legge 991\/1952, oltre a stabilire i criteri di classificazione geomorfologici (l&#8217;80% della superficie al di sopra dei 600 metri o un dislivello maggiore di 600 metri) e di tipo reddituale dei terreni (reddito imponibile medio per ettaro inferiore a 2.400 lire), disponeva che la commissione censuaria centrale istituita presso il Ministero delle Finanze fosse incaricata di stilare e mantenere il conseguente elenco dei comuni montani e poteva includere tra i territori montani anche comuni che, in deroga alle condizioni sopra citate, fossero gi\u00e0 classificati come montani dal catasto agrario o danneggiati da eventi bellici (art 1) o appartenenti a comprensori di bonifica montana (art. 14). Ma l&#8217;abrogazione degli articoli 1 e 14, avvenuta con una successiva norma (legge 142\/1990), ha di fatto impedito la possibilit\u00e0 di rivedere e\/o aggiornare tale classificazione.<\/p><\/blockquote>\n<\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>A\u00a0poche ore dalla scadenza dei termini di pagamento dell\u2019Imu agricola, fissati per il \u00a010 febbraio, l\u2019Istat ha disconosciuto con una nota ufficiale\u00a0di essere responsabile della classificazione dei comuni montani utilizzata per la quantificazione della tassa. In merito alle notizie pubblicate in questi giorni dai mezzi di informazione, che imputano all&#8217;Istat la classificazione dei comuni montani &hellip; <a href=\"https:\/\/web.quotidianopiemontese.it\/agricoltura-in-piemonte\/listat-disconosce-la-classificazione-dei-comuni-montani-usata-per-limu-agricola\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;L&#8217;Istat disconosce la classificazione dei comuni montani usata per l&#8217;Imu agricola&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[10],"class_list":["post-34","post","type-post","status-publish","format-standard","hentry","category-agricoltura","tag-imu-agricola"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&#039;Istat disconosce la classificazione dei comuni montani usata per l&#039;Imu agricola - Agricoltura in Piemonte<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/web.quotidianopiemontese.it\/agricoltura-in-piemonte\/listat-disconosce-la-classificazione-dei-comuni-montani-usata-per-limu-agricola\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;Istat disconosce la classificazione dei comuni montani usata per l&#039;Imu agricola - Agricoltura in Piemonte\" \/>\n<meta property=\"og:description\" content=\"A\u00a0poche ore dalla scadenza dei termini di pagamento dell\u2019Imu agricola, fissati per il \u00a010 febbraio, l\u2019Istat ha disconosciuto con una nota ufficiale\u00a0di essere responsabile della classificazione dei comuni montani utilizzata per la quantificazione della tassa. In merito alle notizie pubblicate in questi giorni dai mezzi di informazione, che imputano all&#8217;Istat la classificazione dei comuni montani &hellip; Leggi tutto &quot;L&#8217;Istat disconosce la classificazione dei comuni montani usata per l&#8217;Imu agricola&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/web.quotidianopiemontese.it\/agricoltura-in-piemonte\/listat-disconosce-la-classificazione-dei-comuni-montani-usata-per-limu-agricola\/\" \/>\n<meta property=\"og:site_name\" content=\"Agricoltura in Piemonte\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese\" \/>\n<meta property=\"article:published_time\" content=\"2015-02-11T08:31:55+00:00\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/agricoltura-in-piemonte\\\/listat-disconosce-la-classificazione-dei-comuni-montani-usata-per-limu-agricola\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/agricoltura-in-piemonte\\\/listat-disconosce-la-classificazione-dei-comuni-montani-usata-per-limu-agricola\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/agricoltura-in-piemonte\\\/#\\\/schema\\\/person\\\/92b86f27cfe3bd649bd878d4f9c88190\"},\"headline\":\"L&#8217;Istat disconosce la classificazione dei comuni montani usata per l&#8217;Imu agricola\",\"datePublished\":\"2015-02-11T08:31:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/agricoltura-in-piemonte\\\/listat-disconosce-la-classificazione-dei-comuni-montani-usata-per-limu-agricola\\\/\"},\"wordCount\":301,\"commentCount\":0,\"keywords\":[\"imu agricola\"],\"articleSection\":[\"Agricoltura\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/agricoltura-in-piemonte\\\/listat-disconosce-la-classificazione-dei-comuni-montani-usata-per-limu-agricola\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/agricoltura-in-piemonte\\\/listat-disconosce-la-classificazione-dei-comuni-montani-usata-per-limu-agricola\\\/\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/agricoltura-in-piemonte\\\/listat-disconosce-la-classificazione-dei-comuni-montani-usata-per-limu-agricola\\\/\",\"name\":\"L'Istat disconosce la classificazione dei comuni montani usata per l'Imu agricola - Agricoltura in Piemonte\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/agricoltura-in-piemonte\\\/#website\"},\"datePublished\":\"2015-02-11T08:31:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/agricoltura-in-piemonte\\\/#\\\/schema\\\/person\\\/92b86f27cfe3bd649bd878d4f9c88190\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/web.quotidianopiemontese.it\\\/agricoltura-in-piemonte\\\/listat-disconosce-la-classificazione-dei-comuni-montani-usata-per-limu-agricola\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/agricoltura-in-piemonte\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/agricoltura-in-piemonte\\\/\",\"name\":\"Agricoltura in Piemonte\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/agricoltura-in-piemonte\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/agricoltura-in-piemonte\\\/#\\\/schema\\\/person\\\/92b86f27cfe3bd649bd878d4f9c88190\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"Quotidiano Piemontese: il sito di informazione pi\u00f9 letto del Piemonte : libero, tempestivo indipendente, social. L'hub sociale e informativo del Piemonte\",\"sameAs\":[\"http:\\\/\\\/www.quotidianopiemontese.it\\\/\",\"https:\\\/\\\/www.facebook.com\\\/quotidianopiemontese\",\"https:\\\/\\\/x.com\\\/quotidianopiem\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/agricoltura-in-piemonte\\\/author\\\/administrator\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'Istat disconosce la classificazione dei comuni montani usata per l'Imu agricola - Agricoltura in Piemonte","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/web.quotidianopiemontese.it\/agricoltura-in-piemonte\/listat-disconosce-la-classificazione-dei-comuni-montani-usata-per-limu-agricola\/","og_locale":"it_IT","og_type":"article","og_title":"L'Istat disconosce la classificazione dei comuni montani usata per l'Imu agricola - Agricoltura in Piemonte","og_description":"A\u00a0poche ore dalla scadenza dei termini di pagamento dell\u2019Imu agricola, fissati per il \u00a010 febbraio, l\u2019Istat ha disconosciuto con una nota ufficiale\u00a0di essere responsabile della classificazione dei comuni montani utilizzata per la quantificazione della tassa. In merito alle notizie pubblicate in questi giorni dai mezzi di informazione, che imputano all&#8217;Istat la classificazione dei comuni montani &hellip; Leggi tutto \"L&#8217;Istat disconosce la classificazione dei comuni montani usata per l&#8217;Imu agricola\"","og_url":"https:\/\/web.quotidianopiemontese.it\/agricoltura-in-piemonte\/listat-disconosce-la-classificazione-dei-comuni-montani-usata-per-limu-agricola\/","og_site_name":"Agricoltura in Piemonte","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_author":"https:\/\/www.facebook.com\/quotidianopiemontese","article_published_time":"2015-02-11T08:31:55+00:00","author":"Redazione","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/web.quotidianopiemontese.it\/agricoltura-in-piemonte\/listat-disconosce-la-classificazione-dei-comuni-montani-usata-per-limu-agricola\/#article","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/agricoltura-in-piemonte\/listat-disconosce-la-classificazione-dei-comuni-montani-usata-per-limu-agricola\/"},"author":{"name":"Redazione","@id":"https:\/\/web.quotidianopiemontese.it\/agricoltura-in-piemonte\/#\/schema\/person\/92b86f27cfe3bd649bd878d4f9c88190"},"headline":"L&#8217;Istat disconosce la classificazione dei comuni montani usata per l&#8217;Imu agricola","datePublished":"2015-02-11T08:31:55+00:00","mainEntityOfPage":{"@id":"https:\/\/web.quotidianopiemontese.it\/agricoltura-in-piemonte\/listat-disconosce-la-classificazione-dei-comuni-montani-usata-per-limu-agricola\/"},"wordCount":301,"commentCount":0,"keywords":["imu agricola"],"articleSection":["Agricoltura"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/web.quotidianopiemontese.it\/agricoltura-in-piemonte\/listat-disconosce-la-classificazione-dei-comuni-montani-usata-per-limu-agricola\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/web.quotidianopiemontese.it\/agricoltura-in-piemonte\/listat-disconosce-la-classificazione-dei-comuni-montani-usata-per-limu-agricola\/","url":"https:\/\/web.quotidianopiemontese.it\/agricoltura-in-piemonte\/listat-disconosce-la-classificazione-dei-comuni-montani-usata-per-limu-agricola\/","name":"L'Istat disconosce la classificazione dei comuni montani usata per l'Imu agricola - Agricoltura in Piemonte","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/agricoltura-in-piemonte\/#website"},"datePublished":"2015-02-11T08:31:55+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/agricoltura-in-piemonte\/#\/schema\/person\/92b86f27cfe3bd649bd878d4f9c88190"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/web.quotidianopiemontese.it\/agricoltura-in-piemonte\/listat-disconosce-la-classificazione-dei-comuni-montani-usata-per-limu-agricola\/"]}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/agricoltura-in-piemonte\/#website","url":"https:\/\/web.quotidianopiemontese.it\/agricoltura-in-piemonte\/","name":"Agricoltura in Piemonte","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/agricoltura-in-piemonte\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/agricoltura-in-piemonte\/#\/schema\/person\/92b86f27cfe3bd649bd878d4f9c88190","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g","caption":"Redazione"},"description":"Quotidiano Piemontese: il sito di informazione pi\u00f9 letto del Piemonte : libero, tempestivo indipendente, social. L'hub sociale e informativo del Piemonte","sameAs":["http:\/\/www.quotidianopiemontese.it\/","https:\/\/www.facebook.com\/quotidianopiemontese","https:\/\/x.com\/quotidianopiem"],"url":"https:\/\/web.quotidianopiemontese.it\/agricoltura-in-piemonte\/author\/administrator\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/agricoltura-in-piemonte\/wp-json\/wp\/v2\/posts\/34","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/agricoltura-in-piemonte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/agricoltura-in-piemonte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/agricoltura-in-piemonte\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/agricoltura-in-piemonte\/wp-json\/wp\/v2\/comments?post=34"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/agricoltura-in-piemonte\/wp-json\/wp\/v2\/posts\/34\/revisions"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/agricoltura-in-piemonte\/wp-json\/wp\/v2\/media?parent=34"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/agricoltura-in-piemonte\/wp-json\/wp\/v2\/categories?post=34"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/agricoltura-in-piemonte\/wp-json\/wp\/v2\/tags?post=34"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}