{"id":25,"date":"2014-12-16T08:00:19","date_gmt":"2014-12-16T07:00:19","guid":{"rendered":"http:\/\/www.quotidianopiemontese.it\/agricoltura-in-piemonte\/?p=25"},"modified":"2014-12-16T01:24:41","modified_gmt":"2014-12-16T00:24:41","slug":"e-morta-solo-43-anni-marzia-serasso-direttrice-regionale-della-confederazione-italiana-agricoltori","status":"publish","type":"post","link":"https:\/\/web.quotidianopiemontese.it\/agricoltura-in-piemonte\/e-morta-solo-43-anni-marzia-serasso-direttrice-regionale-della-confederazione-italiana-agricoltori\/","title":{"rendered":"E morta a solo 43 anni Marzia Serasso direttrice regionale della Confederazione Italiana Agricoltori"},"content":{"rendered":"<p>E\u2019 mancata improvvisamente, il 14 dicembre, all\u2019et\u00e0 di soli 43 anni, la direttrice regionale della<a href=\"http:\/\/www.ciapiemonte.it\/\" target=\"_blank\"> Confederazione Italiana Agricoltori<\/a> del Piemonte Marzia Serasso.<br \/>\nEntrata giovanissima nelle fila della Cia, dopo essersi diplomata agrotecnico presso L&#8217;Istituto Dalmasso di Pianezza si dedic\u00f2 all&#8217;attivit\u00e0 di tecnico-formatore presso la Cia di Torino, nella zona del Chierese, al servizio delle aziende agricole. Successivamente fu chiamata ad operare presso la Cia regionale, prima nell&#8217;ambito della struttura tecnica e poi della struttura politico-sindacale, assolvendo tutti i compiti che le venivano via via assegnati con grande capacit\u00e0, fino a ricevere nel 2010 l&#8217;incarico di Direttrice regionale, dando in questo ruolo un importante contributo al radicamento dell&#8217;Organizzazione nel mondo agricolo ed essendo apprezzata da tutti per le sue qualit\u00e0 umane e la sua competenza.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>E\u2019 mancata improvvisamente, il 14 dicembre, all\u2019et\u00e0 di soli 43 anni, la direttrice regionale della Confederazione Italiana Agricoltori del Piemonte Marzia Serasso. Entrata giovanissima nelle fila della Cia, dopo essersi diplomata agrotecnico presso L&#8217;Istituto Dalmasso di Pianezza si dedic\u00f2 all&#8217;attivit\u00e0 di tecnico-formatore presso la Cia di Torino, nella zona del Chierese, al servizio delle aziende &hellip; <a href=\"https:\/\/web.quotidianopiemontese.it\/agricoltura-in-piemonte\/e-morta-solo-43-anni-marzia-serasso-direttrice-regionale-della-confederazione-italiana-agricoltori\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;E morta a solo 43 anni Marzia Serasso direttrice regionale della Confederazione Italiana Agricoltori&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,9],"tags":[],"class_list":["post-25","post","type-post","status-publish","format-standard","hentry","category-agricoltura","category-associazioni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>E morta a solo 43 anni Marzia Serasso direttrice regionale della Confederazione Italiana Agricoltori - Agricoltura in Piemonte<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/web.quotidianopiemontese.it\/agricoltura-in-piemonte\/e-morta-solo-43-anni-marzia-serasso-direttrice-regionale-della-confederazione-italiana-agricoltori\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"E morta a solo 43 anni Marzia Serasso direttrice regionale della Confederazione Italiana Agricoltori - Agricoltura in Piemonte\" \/>\n<meta property=\"og:description\" content=\"E\u2019 mancata improvvisamente, il 14 dicembre, all\u2019et\u00e0 di soli 43 anni, la direttrice regionale della Confederazione Italiana Agricoltori del Piemonte Marzia Serasso. Entrata giovanissima nelle fila della Cia, dopo essersi diplomata agrotecnico presso L&#8217;Istituto Dalmasso di Pianezza si dedic\u00f2 all&#8217;attivit\u00e0 di tecnico-formatore presso la Cia di Torino, nella zona del Chierese, al servizio delle aziende &hellip; Leggi tutto &quot;E morta a solo 43 anni Marzia Serasso direttrice regionale della Confederazione Italiana Agricoltori&quot;\" \/>\n<meta property=\"og:url\" content=\"http:\/\/web.quotidianopiemontese.it\/agricoltura-in-piemonte\/e-morta-solo-43-anni-marzia-serasso-direttrice-regionale-della-confederazione-italiana-agricoltori\/\" \/>\n<meta property=\"og:site_name\" content=\"Agricoltura in Piemonte\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/quotidianopiemontese\" \/>\n<meta property=\"article:published_time\" content=\"2014-12-16T07:00:19+00:00\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/agricoltura-in-piemonte\\\/e-morta-solo-43-anni-marzia-serasso-direttrice-regionale-della-confederazione-italiana-agricoltori\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/agricoltura-in-piemonte\\\/e-morta-solo-43-anni-marzia-serasso-direttrice-regionale-della-confederazione-italiana-agricoltori\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/agricoltura-in-piemonte\\\/#\\\/schema\\\/person\\\/92b86f27cfe3bd649bd878d4f9c88190\"},\"headline\":\"E morta a solo 43 anni Marzia Serasso direttrice regionale della Confederazione Italiana Agricoltori\",\"datePublished\":\"2014-12-16T07:00:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/agricoltura-in-piemonte\\\/e-morta-solo-43-anni-marzia-serasso-direttrice-regionale-della-confederazione-italiana-agricoltori\\\/\"},\"wordCount\":140,\"commentCount\":0,\"articleSection\":[\"Agricoltura\",\"Associazioni\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"http:\\\/\\\/web.quotidianopiemontese.it\\\/agricoltura-in-piemonte\\\/e-morta-solo-43-anni-marzia-serasso-direttrice-regionale-della-confederazione-italiana-agricoltori\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/agricoltura-in-piemonte\\\/e-morta-solo-43-anni-marzia-serasso-direttrice-regionale-della-confederazione-italiana-agricoltori\\\/\",\"url\":\"http:\\\/\\\/web.quotidianopiemontese.it\\\/agricoltura-in-piemonte\\\/e-morta-solo-43-anni-marzia-serasso-direttrice-regionale-della-confederazione-italiana-agricoltori\\\/\",\"name\":\"E morta a solo 43 anni Marzia Serasso direttrice regionale della Confederazione Italiana Agricoltori - Agricoltura in Piemonte\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/agricoltura-in-piemonte\\\/#website\"},\"datePublished\":\"2014-12-16T07:00:19+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/agricoltura-in-piemonte\\\/#\\\/schema\\\/person\\\/92b86f27cfe3bd649bd878d4f9c88190\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/web.quotidianopiemontese.it\\\/agricoltura-in-piemonte\\\/e-morta-solo-43-anni-marzia-serasso-direttrice-regionale-della-confederazione-italiana-agricoltori\\\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/agricoltura-in-piemonte\\\/#website\",\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/agricoltura-in-piemonte\\\/\",\"name\":\"Agricoltura in Piemonte\",\"description\":\"Quotidiano Piemontese\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/agricoltura-in-piemonte\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/agricoltura-in-piemonte\\\/#\\\/schema\\\/person\\\/92b86f27cfe3bd649bd878d4f9c88190\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"Quotidiano Piemontese: il sito di informazione pi\u00f9 letto del Piemonte : libero, tempestivo indipendente, social. L'hub sociale e informativo del Piemonte\",\"sameAs\":[\"http:\\\/\\\/www.quotidianopiemontese.it\\\/\",\"https:\\\/\\\/www.facebook.com\\\/quotidianopiemontese\",\"https:\\\/\\\/x.com\\\/quotidianopiem\"],\"url\":\"https:\\\/\\\/web.quotidianopiemontese.it\\\/agricoltura-in-piemonte\\\/author\\\/administrator\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"E morta a solo 43 anni Marzia Serasso direttrice regionale della Confederazione Italiana Agricoltori - Agricoltura in Piemonte","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/web.quotidianopiemontese.it\/agricoltura-in-piemonte\/e-morta-solo-43-anni-marzia-serasso-direttrice-regionale-della-confederazione-italiana-agricoltori\/","og_locale":"it_IT","og_type":"article","og_title":"E morta a solo 43 anni Marzia Serasso direttrice regionale della Confederazione Italiana Agricoltori - Agricoltura in Piemonte","og_description":"E\u2019 mancata improvvisamente, il 14 dicembre, all\u2019et\u00e0 di soli 43 anni, la direttrice regionale della Confederazione Italiana Agricoltori del Piemonte Marzia Serasso. Entrata giovanissima nelle fila della Cia, dopo essersi diplomata agrotecnico presso L&#8217;Istituto Dalmasso di Pianezza si dedic\u00f2 all&#8217;attivit\u00e0 di tecnico-formatore presso la Cia di Torino, nella zona del Chierese, al servizio delle aziende &hellip; Leggi tutto \"E morta a solo 43 anni Marzia Serasso direttrice regionale della Confederazione Italiana Agricoltori\"","og_url":"http:\/\/web.quotidianopiemontese.it\/agricoltura-in-piemonte\/e-morta-solo-43-anni-marzia-serasso-direttrice-regionale-della-confederazione-italiana-agricoltori\/","og_site_name":"Agricoltura in Piemonte","article_publisher":"https:\/\/www.facebook.com\/quotidianopiemontese?fref=ts","article_author":"https:\/\/www.facebook.com\/quotidianopiemontese","article_published_time":"2014-12-16T07:00:19+00:00","author":"Redazione","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/web.quotidianopiemontese.it\/agricoltura-in-piemonte\/e-morta-solo-43-anni-marzia-serasso-direttrice-regionale-della-confederazione-italiana-agricoltori\/#article","isPartOf":{"@id":"http:\/\/web.quotidianopiemontese.it\/agricoltura-in-piemonte\/e-morta-solo-43-anni-marzia-serasso-direttrice-regionale-della-confederazione-italiana-agricoltori\/"},"author":{"name":"Redazione","@id":"https:\/\/web.quotidianopiemontese.it\/agricoltura-in-piemonte\/#\/schema\/person\/92b86f27cfe3bd649bd878d4f9c88190"},"headline":"E morta a solo 43 anni Marzia Serasso direttrice regionale della Confederazione Italiana Agricoltori","datePublished":"2014-12-16T07:00:19+00:00","mainEntityOfPage":{"@id":"http:\/\/web.quotidianopiemontese.it\/agricoltura-in-piemonte\/e-morta-solo-43-anni-marzia-serasso-direttrice-regionale-della-confederazione-italiana-agricoltori\/"},"wordCount":140,"commentCount":0,"articleSection":["Agricoltura","Associazioni"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["http:\/\/web.quotidianopiemontese.it\/agricoltura-in-piemonte\/e-morta-solo-43-anni-marzia-serasso-direttrice-regionale-della-confederazione-italiana-agricoltori\/#respond"]}]},{"@type":"WebPage","@id":"http:\/\/web.quotidianopiemontese.it\/agricoltura-in-piemonte\/e-morta-solo-43-anni-marzia-serasso-direttrice-regionale-della-confederazione-italiana-agricoltori\/","url":"http:\/\/web.quotidianopiemontese.it\/agricoltura-in-piemonte\/e-morta-solo-43-anni-marzia-serasso-direttrice-regionale-della-confederazione-italiana-agricoltori\/","name":"E morta a solo 43 anni Marzia Serasso direttrice regionale della Confederazione Italiana Agricoltori - Agricoltura in Piemonte","isPartOf":{"@id":"https:\/\/web.quotidianopiemontese.it\/agricoltura-in-piemonte\/#website"},"datePublished":"2014-12-16T07:00:19+00:00","author":{"@id":"https:\/\/web.quotidianopiemontese.it\/agricoltura-in-piemonte\/#\/schema\/person\/92b86f27cfe3bd649bd878d4f9c88190"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["http:\/\/web.quotidianopiemontese.it\/agricoltura-in-piemonte\/e-morta-solo-43-anni-marzia-serasso-direttrice-regionale-della-confederazione-italiana-agricoltori\/"]}]},{"@type":"WebSite","@id":"https:\/\/web.quotidianopiemontese.it\/agricoltura-in-piemonte\/#website","url":"https:\/\/web.quotidianopiemontese.it\/agricoltura-in-piemonte\/","name":"Agricoltura in Piemonte","description":"Quotidiano Piemontese","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/web.quotidianopiemontese.it\/agricoltura-in-piemonte\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/web.quotidianopiemontese.it\/agricoltura-in-piemonte\/#\/schema\/person\/92b86f27cfe3bd649bd878d4f9c88190","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fdce1b5a74767a43870aca54b0800bed88aab98b8098f69ac252d11aec8cdbe7?s=96&d=mm&r=g","caption":"Redazione"},"description":"Quotidiano Piemontese: il sito di informazione pi\u00f9 letto del Piemonte : libero, tempestivo indipendente, social. L'hub sociale e informativo del Piemonte","sameAs":["http:\/\/www.quotidianopiemontese.it\/","https:\/\/www.facebook.com\/quotidianopiemontese","https:\/\/x.com\/quotidianopiem"],"url":"https:\/\/web.quotidianopiemontese.it\/agricoltura-in-piemonte\/author\/administrator\/"}]}},"_links":{"self":[{"href":"https:\/\/web.quotidianopiemontese.it\/agricoltura-in-piemonte\/wp-json\/wp\/v2\/posts\/25","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.quotidianopiemontese.it\/agricoltura-in-piemonte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.quotidianopiemontese.it\/agricoltura-in-piemonte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/agricoltura-in-piemonte\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/agricoltura-in-piemonte\/wp-json\/wp\/v2\/comments?post=25"}],"version-history":[{"count":0,"href":"https:\/\/web.quotidianopiemontese.it\/agricoltura-in-piemonte\/wp-json\/wp\/v2\/posts\/25\/revisions"}],"wp:attachment":[{"href":"https:\/\/web.quotidianopiemontese.it\/agricoltura-in-piemonte\/wp-json\/wp\/v2\/media?parent=25"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/agricoltura-in-piemonte\/wp-json\/wp\/v2\/categories?post=25"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.quotidianopiemontese.it\/agricoltura-in-piemonte\/wp-json\/wp\/v2\/tags?post=25"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}